{"id":10100,"date":"2024-09-16T15:22:35","date_gmt":"2024-09-16T18:22:35","guid":{"rendered":"https:\/\/eval.cl\/?post_type=product&#038;p=10100"},"modified":"2024-09-16T15:22:36","modified_gmt":"2024-09-16T18:22:36","slug":"tableros-electrico","status":"publish","type":"product","link":"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/","title":{"rendered":"\u00a0Tableros el\u00e9ctrico"},"content":{"rendered":"<p>Tableros el\u00e9ctricos para equipos de elevaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tableros el\u00e9ctricos para equipos de elevaci\u00f3n.<\/p>\n","protected":false},"featured_media":10101,"template":"","meta":[],"product_cat":[118],"product_tag":[],"class_list":{"0":"post-10100","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-repuesto-y-accesorios-para-puentes-gruas","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00a0Tableros el\u00e9ctrico - Eval<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a0Tableros el\u00e9ctrico - Eval\" \/>\n<meta property=\"og:description\" content=\"Tableros el\u00e9ctricos para equipos de elevaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/\" \/>\n<meta property=\"og:site_name\" content=\"Eval\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-16T18:22:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eval.cl\/wp-content\/uploads\/2024\/09\/Tableros-electricos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1179\" \/>\n\t<meta property=\"og:image:height\" content=\"663\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/\",\"url\":\"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/\",\"name\":\"\u00a0Tableros el\u00e9ctrico - Eval\",\"isPartOf\":{\"@id\":\"https:\/\/eval.cl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eval.cl\/wp-content\/uploads\/2024\/09\/Tableros-electricos.jpg\",\"datePublished\":\"2024-09-16T18:22:35+00:00\",\"dateModified\":\"2024-09-16T18:22:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/#primaryimage\",\"url\":\"https:\/\/eval.cl\/wp-content\/uploads\/2024\/09\/Tableros-electricos.jpg\",\"contentUrl\":\"https:\/\/eval.cl\/wp-content\/uploads\/2024\/09\/Tableros-electricos.jpg\",\"width\":1179,\"height\":663,\"caption\":\"Tableros el\u00e9ctricos para equipos de elevaci\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/eval.cl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/eval.cl\/index.php\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00a0Tableros el\u00e9ctrico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eval.cl\/#website\",\"url\":\"https:\/\/eval.cl\/\",\"name\":\"Eval\",\"description\":\"Puente Gr\u00faa, Gr\u00faa Viajera, Fabricaci\u00f3n de Puente Gr\u00faa, Instalaci\u00f3n de Puente Gr\u00faa, Gr\u00faa Portal, Gr\u00faa P\u00f3rtico con Neum\u00e1ticos, Gr\u00faa Puerto RTG, Repuestos y Accesorios\",\"publisher\":{\"@id\":\"https:\/\/eval.cl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eval.cl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/eval.cl\/#organization\",\"name\":\"Eval\",\"url\":\"https:\/\/eval.cl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/eval.cl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/eval.cl\/wp-content\/uploads\/2017\/07\/REDISENO-EVAL-04.webp\",\"contentUrl\":\"https:\/\/eval.cl\/wp-content\/uploads\/2017\/07\/REDISENO-EVAL-04.webp\",\"width\":160,\"height\":83,\"caption\":\"Eval\"},\"image\":{\"@id\":\"https:\/\/eval.cl\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a0Tableros el\u00e9ctrico - Eval","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a0Tableros el\u00e9ctrico - Eval","og_description":"Tableros el\u00e9ctricos para equipos de elevaci\u00f3n.","og_url":"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/","og_site_name":"Eval","article_modified_time":"2024-09-16T18:22:36+00:00","og_image":[{"width":1179,"height":663,"url":"https:\/\/eval.cl\/wp-content\/uploads\/2024\/09\/Tableros-electricos.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/","url":"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/","name":"\u00a0Tableros el\u00e9ctrico - Eval","isPartOf":{"@id":"https:\/\/eval.cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/#primaryimage"},"image":{"@id":"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/#primaryimage"},"thumbnailUrl":"https:\/\/eval.cl\/wp-content\/uploads\/2024\/09\/Tableros-electricos.jpg","datePublished":"2024-09-16T18:22:35+00:00","dateModified":"2024-09-16T18:22:36+00:00","breadcrumb":{"@id":"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/#primaryimage","url":"https:\/\/eval.cl\/wp-content\/uploads\/2024\/09\/Tableros-electricos.jpg","contentUrl":"https:\/\/eval.cl\/wp-content\/uploads\/2024\/09\/Tableros-electricos.jpg","width":1179,"height":663,"caption":"Tableros el\u00e9ctricos para equipos de elevaci\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/eval.cl\/index.php\/producto\/tableros-electrico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eval.cl\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/eval.cl\/index.php\/tienda\/"},{"@type":"ListItem","position":3,"name":"\u00a0Tableros el\u00e9ctrico"}]},{"@type":"WebSite","@id":"https:\/\/eval.cl\/#website","url":"https:\/\/eval.cl\/","name":"Eval","description":"Puente Gr\u00faa, Gr\u00faa Viajera, Fabricaci\u00f3n de Puente Gr\u00faa, Instalaci\u00f3n de Puente Gr\u00faa, Gr\u00faa Portal, Gr\u00faa P\u00f3rtico con Neum\u00e1ticos, Gr\u00faa Puerto RTG, Repuestos y Accesorios","publisher":{"@id":"https:\/\/eval.cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eval.cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/eval.cl\/#organization","name":"Eval","url":"https:\/\/eval.cl\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eval.cl\/#\/schema\/logo\/image\/","url":"https:\/\/eval.cl\/wp-content\/uploads\/2017\/07\/REDISENO-EVAL-04.webp","contentUrl":"https:\/\/eval.cl\/wp-content\/uploads\/2017\/07\/REDISENO-EVAL-04.webp","width":160,"height":83,"caption":"Eval"},"image":{"@id":"https:\/\/eval.cl\/#\/schema\/logo\/image\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/eval.cl\/index.php\/wp-json\/wp\/v2\/product\/10100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eval.cl\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eval.cl\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eval.cl\/index.php\/wp-json\/wp\/v2\/media\/10101"}],"wp:attachment":[{"href":"https:\/\/eval.cl\/index.php\/wp-json\/wp\/v2\/media?parent=10100"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eval.cl\/index.php\/wp-json\/wp\/v2\/product_cat?post=10100"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eval.cl\/index.php\/wp-json\/wp\/v2\/product_tag?post=10100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}